{"id":20078,"date":"2018-07-19T09:49:11","date_gmt":"2018-07-19T08:49:11","guid":{"rendered":"https:\/\/soprassub.com\/shop\/double-port-valve-300-bar\/"},"modified":"2026-05-30T14:27:12","modified_gmt":"2026-05-30T13:27:12","slug":"double-port-valve-300-bar","status":"publish","type":"product","link":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/","title":{"rendered":"Right H valve 300 bar"},"content":{"rendered":"<p>thread M25x2<\/p>\n<p>300 bar<\/p>\n<p>2 ports<\/p>\n","protected":false},"excerpt":{"rendered":"<p>thread M25x2 300 bar 2 ports<\/p>\n","protected":false},"featured_media":20082,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":""},"product_brand":[],"product_cat":[1441],"product_tag":[],"class_list":["post-20078","product","type-product","status-publish","has-post-thumbnail","product_cat-2-anschluesse","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Right H valve 300 bar - Soprassub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Right H valve 300 bar - Soprassub\" \/>\n<meta property=\"og:description\" content=\"thread M25x2 300 bar 2 ports\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/\" \/>\n<meta property=\"og:site_name\" content=\"Soprassub\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-30T13:27:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soprassub.com\\\/de\\\/shop\\\/double-port-valve-300-bar\\\/\",\"url\":\"https:\\\/\\\/soprassub.com\\\/de\\\/shop\\\/double-port-valve-300-bar\\\/\",\"name\":\"Right H valve 300 bar - Soprassub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soprassub.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soprassub.com\\\/de\\\/shop\\\/double-port-valve-300-bar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soprassub.com\\\/de\\\/shop\\\/double-port-valve-300-bar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soprassub.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/double-port-300bar-2edit.jpg\",\"datePublished\":\"2018-07-19T08:49:11+00:00\",\"dateModified\":\"2026-05-30T13:27:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soprassub.com\\\/de\\\/shop\\\/double-port-valve-300-bar\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soprassub.com\\\/de\\\/shop\\\/double-port-valve-300-bar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/soprassub.com\\\/de\\\/shop\\\/double-port-valve-300-bar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soprassub.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/double-port-300bar-2edit.jpg\",\"contentUrl\":\"https:\\\/\\\/soprassub.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/double-port-300bar-2edit.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soprassub.com\\\/de\\\/shop\\\/double-port-valve-300-bar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/soprassub.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/soprassub.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Right H valve 300 bar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soprassub.com\\\/#website\",\"url\":\"https:\\\/\\\/soprassub.com\\\/\",\"name\":\"Soprassub\",\"description\":\"Recreational diving\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soprassub.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Right H valve 300 bar - Soprassub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/","og_locale":"de_DE","og_type":"article","og_title":"Right H valve 300 bar - Soprassub","og_description":"thread M25x2 300 bar 2 ports","og_url":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/","og_site_name":"Soprassub","article_modified_time":"2026-05-30T13:27:12+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/","url":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/","name":"Right H valve 300 bar - Soprassub","isPartOf":{"@id":"https:\/\/soprassub.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/#primaryimage"},"image":{"@id":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/#primaryimage"},"thumbnailUrl":"https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit.jpg","datePublished":"2018-07-19T08:49:11+00:00","dateModified":"2026-05-30T13:27:12+00:00","breadcrumb":{"@id":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/#primaryimage","url":"https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit.jpg","contentUrl":"https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/soprassub.com\/de\/shop\/double-port-valve-300-bar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/soprassub.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/soprassub.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Right H valve 300 bar"}]},{"@type":"WebSite","@id":"https:\/\/soprassub.com\/#website","url":"https:\/\/soprassub.com\/","name":"Soprassub","description":"Recreational diving","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soprassub.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"uagb_featured_image_src":{"full":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit.jpg",1500,1500,false],"thumbnail":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit-150x150.jpg",150,150,true],"medium":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit-300x300.jpg",300,300,true],"medium_large":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit-768x768.jpg",768,768,true],"large":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit.jpg",1500,1500,false],"2048x2048":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit.jpg",1500,1500,false],"neve-blog":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit-930x620.jpg",930,620,true],"mailpoet_newsletter_max":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit.jpg",1320,1320,false],"woocommerce_thumbnail":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit-600x600.jpg",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/soprassub.com\/wp-content\/uploads\/2018\/07\/double-port-300bar-2edit-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"sobkova","author_link":"https:\/\/soprassub.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"thread M25x2 300 bar 2 ports","_links":{"self":[{"href":"https:\/\/soprassub.com\/de\/wp-json\/wp\/v2\/product\/20078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soprassub.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soprassub.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/soprassub.com\/de\/wp-json\/wp\/v2\/comments?post=20078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soprassub.com\/de\/wp-json\/wp\/v2\/media\/20082"}],"wp:attachment":[{"href":"https:\/\/soprassub.com\/de\/wp-json\/wp\/v2\/media?parent=20078"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soprassub.com\/de\/wp-json\/wp\/v2\/product_brand?post=20078"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soprassub.com\/de\/wp-json\/wp\/v2\/product_cat?post=20078"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soprassub.com\/de\/wp-json\/wp\/v2\/product_tag?post=20078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}